{"id":3851,"date":"2026-01-22T01:05:50","date_gmt":"2026-01-22T00:05:50","guid":{"rendered":"https:\/\/fetean.org\/?post_type=catalogo&#038;p=3851"},"modified":"2026-03-30T00:51:41","modified_gmt":"2026-03-29T23:51:41","slug":"el-abanico-de-adela","status":"publish","type":"catalogo","link":"https:\/\/fetean.org\/eu\/catalogo\/el-abanico-de-adela\/","title":{"rendered":"El abanico de Adela"},"excerpt":{"rendered":"<p>En una casa cerrada al mundo exterior, Bernarda impone una autoridad f\u00e9rrea sobre sus hijas, convirtiendo el silencio y la obediencia en normas de vida. En este lugar, Adela irrumpe como s\u00edmbolo de juventud, deseo y ansia de libertad. Su enfrentamiento con la norma materna y con el destino impuesto, desencadena una tensi\u00f3n creciente entre las hermanas. La obra es una adaptaci\u00f3n del cl\u00e1sico \u00abLa casa de Bernarda Alba\u00bb.<\/p>","protected":false},"featured_media":3854,"template":"","genero":[23],"class_list":["post-3851","catalogo","type-catalogo","status-publish","has-post-thumbnail","hentry","portfolio-vis-active"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/fetean.org\/eu\/wp-json\/wp\/v2\/catalogo\/3851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fetean.org\/eu\/wp-json\/wp\/v2\/catalogo"}],"about":[{"href":"https:\/\/fetean.org\/eu\/wp-json\/wp\/v2\/types\/catalogo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fetean.org\/eu\/wp-json\/wp\/v2\/media\/3854"}],"wp:attachment":[{"href":"https:\/\/fetean.org\/eu\/wp-json\/wp\/v2\/media?parent=3851"}],"wp:term":[{"taxonomy":"genero","embeddable":true,"href":"https:\/\/fetean.org\/eu\/wp-json\/wp\/v2\/genero?post=3851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}